{"id":1151,"date":"2021-05-30T15:18:01","date_gmt":"2021-05-30T15:18:01","guid":{"rendered":"http:\/\/msaludsgo.gov.ar\/web\/?p=1151"},"modified":"2021-05-31T17:45:46","modified_gmt":"2021-05-31T17:45:46","slug":"la-vacunacion-contra-el-coronavirus-tuvo-un-fuerte-avance-esta-semana","status":"publish","type":"post","link":"https:\/\/msaludsgo.gov.ar\/web\/la-vacunacion-contra-el-coronavirus-tuvo-un-fuerte-avance-esta-semana\/","title":{"rendered":"La vacunaci\u00f3n contra el coronavirus tuvo un fuerte avance esta semana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El Ministerio de salud inform\u00f3 que en 4 d\u00edas se colocaron 19.929 dosis y se busca incrementar este n\u00famero en la pr\u00f3xima semana con el env\u00edo de una nueva partida desde la Naci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con un importante operativo de vacunaci\u00f3n, del que participan cientos de trabajadores del primer nivel de atenci\u00f3n distribuidos en distintos centros de vacunaci\u00f3n de forma simult\u00e1nea -tanto en Capital y La Banda como en el interior de la provincia-, esta semana se logr\u00f3 inmunizar con primera dosis a personas con factores de riesgo, docentes secundarios y adultos mayores en el interior. Adem\u00e1s, esta semana se implement\u00f3 una estrategia diferenciada para la vacunaci\u00f3n de personas con factor de riesgo de obesidad. M\u00e1s de 3800 personas con esta condici\u00f3n se vacunaron en los \u00faltimos 3 d\u00edas y contin\u00faan registr\u00e1ndose en UPAs, CAps, CAMs y hospitales del interior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Una cuidadosa organizaci\u00f3n, que abarca la programaci\u00f3n de turnos, el operativo de traslado de la vacuna, la recepci\u00f3n y registro de las personas, la vacunaci\u00f3n y el control pos vacunal est\u00e1 haciendo posible avanzar con eficacia cumpliendo las metas de proteger a la poblaci\u00f3n m\u00e1s vulnerable, semana tras semana.<br>Durante los pr\u00f3ximos d\u00edas est\u00e1 previsto ampliar la poblaci\u00f3n vacunando personas de 50 a 59 a\u00f1os y continuar con vacunaci\u00f3n de personas de distintos grupos de riesgo en el interior de la provincia. Adem\u00e1s se colocar\u00e1 la segunda dosis a las personas con condiciones de riesgo que recibieron la primera dosis el 29 y 30 de abril.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo ser\u00e1 el cronograma?<\/strong><br>Las personas de <strong>55 a 59 a\u00f1os se vacunar\u00e1n con primera dosis los d\u00edas lunes 31 de mayo y el martes 1 de Junio<\/strong> en Ciudad Capital y La Banda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>personas de 50 a 54 a\u00f1os que residen en Capital y La Banda<\/strong> se vacunar\u00e1n con primera dosis los d\u00edas <strong>mi\u00e9rcoles 2 y jueves 3 de junio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los lugares de vacunaci\u00f3n ser\u00e1n: <\/strong>en Capital de 8 a 17 hs.: Club Coronel Borges, Club Nicolas Avellaneda, Club De Veteranos, Club Belgrano, Club Dorrego, Club Alte Brown, Cic Campo Contreras. En La Banda de 8 a las 14 hs: Club Ol\u00edmpico, Centro Recreativo y Club Tiro Federal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los turnos ya est\u00e1n disponibles en https:\/\/vacunarse.sde.gob.ar\/<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, las personas de <strong>50 a 59 a\u00f1os<\/strong> de las ciudades de Termas, Fr\u00edas, A\u00f1atuya, Fern\u00e1ndez, Forres, Beltr\u00e1n y Los Juries, se vacunar\u00e1n con primera dosis entre los d\u00edas mi\u00e9rcoles 2 y el viernes 4 de junio.<br><strong>Los turnos ya est\u00e1n disponibles en https:\/\/vacunarse.sde.gob.ar\/<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, las <strong>personas con factores de riesgo que se recibieron la primera dosis de SInopharm los d\u00edas 29 y 30 de abril,<\/strong> se vacunar\u00e1n con segunda dosis el pr\u00f3ximo viernes 4 de junio desde las 8 a las 17 hs en CAPITAL en los clubes: Independiente, Nicol\u00e1s Avellaneda, Veteranos, Dorrego y Alte Brown y en LA BANDA en el Club Ol\u00edmpico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los turnos ya est\u00e1n disponibles en https:\/\/vacunarse.sde.gob.ar\/<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se colocar\u00e1n segundas dosis a mayores de 60 a\u00f1os en Ojo de Agua los d\u00edas 31 y 1 de junio y primera dosis a personas con factores de riesgo de 18 a 59 a\u00f1os en Bandera el pr\u00f3ximo 31 de mayo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Lunes <strong>31 de Mayo<\/strong> continuar\u00e1 la <strong>vacunaci\u00f3n de docentes secundarios<\/strong> de la Banda en las escuelas. Gorostiaga y Mariano Moreno. Los docentes son notificados por las autoridades educativas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de salud inform\u00f3 que en 4 d\u00edas se colocaron 19.929 dosis y se busca incrementar este n\u00famero en la pr\u00f3xima semana con el env\u00edo de una nueva partida desde la Naci\u00f3n. Con un importante operativo de vacunaci\u00f3n, del que participan cientos de trabajadores del primer nivel de atenci\u00f3n distribuidos en distintos centros de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3,14],"tags":[],"class_list":["post-1151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-novedades","category-vacunacion-covid-19"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":3,"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"predecessor-version":[{"id":1160,"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/posts\/1151\/revisions\/1160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/media\/1152"}],"wp:attachment":[{"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/msaludsgo.gov.ar\/web\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}